{"id":8278,"date":"2016-01-06T00:00:00","date_gmt":"2016-01-06T00:00:00","guid":{"rendered":"https:\/\/sites-stage.familylife.com\/flministries\/?p=8278"},"modified":"2016-01-06T00:00:00","modified_gmt":"2016-01-06T00:00:00","slug":"i-never-made-it-to-the-super-bowl","status":"publish","type":"post","link":"https:\/\/wp-stage.familylife.com\/www\/articles\/topics\/marriage\/staying-married\/husbands\/i-never-made-it-to-the-super-bowl\/","title":{"rendered":"I Never Made It to the Super Bowl"},"content":{"rendered":"<div id=\"bsf_rt_marker\" fetchpriority=\"high\"><\/div><p style=\"background: none repeat scroll 0% 0% white\">It\u2019s that time of year: the NFL playoffs\u2014that time of most intense yearning for fans.<\/p>\n<p>For months fans have been putting their hopes in their teams\u2019 players and coaches, who have been pouring every ounce of mental and physical energy into a singular goal: reaching and winning the Super Bowl. Every team is dying to get there but few do. Fans dream of going to the big game, if they could even afford the $2,800 tickets. Players, coaches, fans\u2014we all yearn for our team to make it.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">My own yearning to go to the big game started early\u2014as a 7-year-old boy. It was around Christmas when my daddy told me that if his team won their big championship game against the Chiefs, I would get to fly to Los Angeles to watch the very first Super Bowl in NFL history. Dad was more than a Buffalo Bills fan\u2014he was their quarterback.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">Dad played hard. We cheered hard. But our California Super Bowl dreams were dashed when Kansas City won the league championship, earning <em>them<\/em> the trip to face the Green Bay Packers in Super Bowl I.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">Less than 20 years later, I had <em>my<\/em> chance to go to the playoffs as quarterback of the Los Angeles Rams, only to lose in the first round. The next year\u2014just like my dad\u2014our team made it all the way to the conference championship game. We weren&#8217;t that close &#8230; we lost to the Bears 24-0 in frigid, windy Chicago.\u00a0But hey, 25 points in the fourth quarter and we&#8217;d have been in the New Orleans Superdome playing in Super Bowl XX.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">One of the best teams I played for, the San Francisco 49ers, went to and won multiple Super Bowls, but not in the single season I was on the team. My teams made it to the playoffs six times, but never to the big game. So I know at least a bit about the yearning and the sacrifices made to reach and win the Super Bowl.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">The best NFL coaches do more than just paint a vivid picture (cast a clear vision) of the Super Bowl as the team&#8217;s goal. They connect every little detail of preparation, practice, and doing your particular assignment as vital to the journey and prize of a Super Bowl championship. I remember Hall of Fame coach Bill Walsh explaining to us how details like perfectly consistent steps in handing off the ball or timing in releasing a pass relate to the constant improvement and excellence that would lead us toward a Super Bowl.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">Laser-like focus is crucial to accomplishing great things in life. The trick seems to be in choosing what steps are important and what goals are truly great.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">Often we are distracted from the ultimate goals and most important things in life. It may be busyness. It may be the sudden blitz of life&#8217;s painful problems.\u00a0It may be the distractions of entertainment, or for us fans, the obsession with a sporting event like the Super Bowl.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">I&#8217;ll be the first to admit it.\u00a0I love the playoffs and I obsess a bit too much about getting to see all the great games, culminating with the Super Bowl.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">But for those of us who believe in and aim to follow Jesus, all the enthusiasm and emotional devotion we have toward the playoffs should trigger a calibrating question:<\/p>\n<p style=\"margin: 0in 0in 0.0001pt 0.5in;background: none repeat scroll 0% 0% white\"><em>How much do other interests of mine crowd out what should be my transcending joy and dominant interest?<\/em><\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">If I can put so much energy into the Super Bowl, how much more focus and effort can I put into my marriage, raising my children to know Christ, preparing them to walk in His purpose for them?<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">God and His Word point us as men to the ultimate goals and destination: seeking first His Kingdom, our eternal relationship with Him, and leading others to the same. Our goal is the upward call of the prize of dwelling with God eternally and elevating our Savior, Jesus. We all love our teams. But this eternal goal should be motivated by gratitude and love for God, who never lets us down. And that should drive us to the daily and the practical: to show our love for Him by loving others, including each person in our family, and every human neighbor He puts in our path.<\/p>\n<p style=\"background: none repeat scroll 0% 0% white\">Friend, you may never get to attend the Super Bowl or accomplish your biggest earthly goal.\u00a0But there are bigger, more attainable goals in Christ.\u00a0This year let the intensity, attention, and extravagance of the Super Bowl prompt us as Jesus followers to refocus on our greatest joy, our greatest victory, and our greatest calling. How should that make us live differently?<\/p>\n<hr \/>\n<p><em>Copyright \u00a9 2014 by FamilyLife. All rights reserved.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As an NFL quarterback, I yearned to make the big game.  But as much as I love football, I realize it can easily distract us from more important goals.<\/p>\n","protected":false},"author":222,"featured_media":8279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uag_custom_page_level_css":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[2901],"tags":[],"equip-category":[],"cwp_profile":[3166],"class_list":["post-8278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-husbands","cwp_profile-jeff-kemp"],"acf":[],"jetpack_featured_media_url":"https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2018\/04\/i-never-made-it-to-the-super-bowl_1040x326.jpg","spectra_custom_meta":{"_wp_page_template":["default"],"_vc_post_settings":["a:1:{s:10:\"vc_grid_id\";a:0:{}}"],"_startdate":["field_598a655fc5a8d"],"startdate":[""],"_state":["field_598a6575c5a8e"],"state":[""],"_url":["field_598a6582c5a8f"],"url":[""],"_venuename":["field_598a6598c5a90"],"venuename":[""],"_hotel_reservationurl":["field_598a65b3c5a91"],"hotel_reservationurl":[""],"_reservationtelephone":["field_598a65c6c5a92"],"reservationtelephone":[""],"_imageurl":["field_598a65edc5a93"],"imageurl":["https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/2016\/01\/i-never-made-it-to-the-super-bowl_1040x326.jpg"],"_postalcode":["field_598a654b146f3"],"postalcode":[""],"_longitude":["field_598a653e355f6"],"longitude":[""],"_latitude":["field_598a64f8ada01"],"latitude":[""],"_enddate":["field_598a64a5afb90"],"enddate":[""],"_countrycode":["field_598a648b86dcc"],"countrycode":[""],"_city":["field_598a647e29bf2"],"city":[""],"_availableseats":["field_598a646bbebc6"],"availableseats":[""],"_addressline1":["field_598a645214a6b"],"addressline1":[""],"_eventid":["field_598a6442626b9"],"eventid":[""],"_thumbnail_id":["8279"],"_cs_replacements":["a:1:{s:12:\"blog-sidebar\";s:4:\"cs-2\";}"],"_alt_author":["field_5ac3df572642e"],"alt_author":["14390"],"_eael_post_view_count":["657"],"_eb_reusable_block_ids":["a:0:{}"],"_uag_css_file_name":["uag-css-8278.css"],"_uag_js_file_name":["uag-js-8278.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:82560:\".wp-block-uagb-container.uagb-block-e11dbe9f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e11dbe9f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e11dbe9f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e11dbe9f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e11dbe9f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e11dbe9f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e11dbe9f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-e11dbe9f{box-shadow: 0px 0px   #00000070 ;padding-top: 3em;padding-bottom: 3em;padding-left: 1.5em;padding-right: 1.5em;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f8f8f8;;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e11dbe9f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e11dbe9f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e11dbe9f{padding-top: 3px;padding-bottom: 3px;padding-left: 1.5px;padding-right: 1.5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f8f8f8;;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e11dbe9f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e11dbe9f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e11dbe9f{padding-top: 3px;padding-bottom: 3px;padding-left: 1.5px;padding-right: 1.5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f8f8f8;;}}.wp-block-uagb-container.uagb-block-85559158 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-85559158 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-85559158 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-85559158 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-85559158 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-85559158{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-85559158 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 960px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-85559158{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 60px !important;margin-bottom: 60px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-ea16301a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ea16301a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ea16301a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ea16301a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ea16301a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ea16301a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ea16301a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ea16301a.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 40px;column-gap: 40px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: start;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ea16301a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-ea16301a.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-ea16301a.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-container.uagb-block-26ccc5c9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-26ccc5c9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-26ccc5c9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-26ccc5c9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-26ccc5c9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-26ccc5c9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-26ccc5c9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-26ccc5c9{min-height: 710px;box-shadow: 3px 7px 7px -1px rgba(0,0,0,0.15) ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;align-self: start;}.wp-block-uagb-container.uagb-block-84f50fa3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-84f50fa3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-84f50fa3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-84f50fa3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-84f50fa3 .uagb-container__video-wrap video{opacity: 1;background: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2024\/07\/Grow-with-your-family_545x307.jpg) 50% 50%;;background-size: cover;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-84f50fa3{max-width: 100vw;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-84f50fa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-84f50fa3{min-height: 250px;box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2025\/03\/Grow-with-your-family_545x307.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-271bf38d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-271bf38d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-271bf38d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-271bf38d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-271bf38d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-271bf38d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-271bf38d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-271bf38d{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-ab8d0982 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ab8d0982 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ab8d0982 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ab8d0982 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ab8d0982 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab8d0982{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab8d0982 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ab8d0982.uagb-layout-grid{row-gap: 8px;column-gap: 8px;grid-template-columns: auto  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ab8d0982{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-ab8d0982.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-ab8d0982.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3.wp-block-uagb-advanced-heading .uagb-heading-text{color: #25282a;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3 .uagb-heading-text{font-weight: 300;font-size: 16px;}.uagb-block-f9d54988.wp-block-uagb-separator{text-align: left;}.uagb-block-f9d54988.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-f9d54988 .uagb-separator-spacing-wrapper{padding-top: 4px;padding-bottom: 4px;}.uagb-block-f9d54988.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 3px;width: 100%;border-top-color: #eabe5e;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-3208cc36.wp-block-uagb-advanced-heading .uagb-heading-text{color: #006a5a;}.wp-block-uagb-advanced-heading.uagb-block-3208cc36.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3208cc36.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3208cc36.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3208cc36.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3208cc36 .uagb-heading-text{font-weight: 400;font-size: 26px;line-height: 1.2em;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__source-image{width: 18px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 18px;height: 18px;font-size: 18px;color: #1573a2;fill: #1573a2;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: em;color: #1573a2;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 24px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__source-wrap{margin-left: 15px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child {flex-direction: row-reverse;}.uagb-block-fdd052c2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-fdd052c2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-679dc0da.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-679dc0da.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-fbb8dca6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-fbb8dca6.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b5e9a44d.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b5e9a44d.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-10525170.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-10525170.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.wp-block-uagb-container.uagb-block-48a597f8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48a597f8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48a597f8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48a597f8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48a597f8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48a597f8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48a597f8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-48a597f8{min-height: 710px;box-shadow: 3px 7px 7px -1px rgba(0,0,0,0.15) ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;align-self: start;}.wp-block-uagb-container.uagb-block-22a41c70 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-22a41c70 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-22a41c70 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-22a41c70 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-22a41c70 .uagb-container__video-wrap video{opacity: 1;background: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2024\/07\/Grow-with-your-family_545x307.jpg) 50% 50%;;background-size: cover;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-22a41c70{max-width: 100vw;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-22a41c70 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-22a41c70{min-height: 250px;box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2025\/03\/HelpFamiliesGrow2.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-562935bf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-562935bf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-562935bf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-562935bf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-562935bf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-562935bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-562935bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-562935bf{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-5a1442f2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5a1442f2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5a1442f2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5a1442f2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5a1442f2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5a1442f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5a1442f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5a1442f2.uagb-layout-grid{row-gap: 8px;column-gap: 8px;grid-template-columns: auto  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5a1442f2{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-5a1442f2.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-5a1442f2.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f.wp-block-uagb-advanced-heading .uagb-heading-text{color: #25282a;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f .uagb-heading-text{font-weight: 300;font-size: 16px;}.uagb-block-aa17f10e.wp-block-uagb-separator{text-align: left;}.uagb-block-aa17f10e.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-aa17f10e .uagb-separator-spacing-wrapper{padding-top: 4px;padding-bottom: 4px;}.uagb-block-aa17f10e.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 3px;width: 100%;border-top-color: #eabe5e;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-31f155e3.wp-block-uagb-advanced-heading .uagb-heading-text{color: #006a5a;}.wp-block-uagb-advanced-heading.uagb-block-31f155e3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-31f155e3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-31f155e3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-31f155e3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-31f155e3 .uagb-heading-text{font-weight: 400;font-size: 26px;line-height: 1.2em;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__source-image{width: 18px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 18px;height: 18px;font-size: 18px;color: #1573a2;fill: #1573a2;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: em;color: #1573a2;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-ced20c64.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 24px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__source-wrap{margin-left: 15px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child {flex-direction: row-reverse;}.uagb-block-83befcbf.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-83befcbf.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-75d2f158.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-75d2f158.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-0d14af90.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-0d14af90.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4dd6f9d3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4dd6f9d3.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-28c58e21.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-28c58e21.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-85559158{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-85559158 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-85559158{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 60px !important;margin-bottom: 60px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ea16301a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ea16301a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ea16301a.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ea16301a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-26ccc5c9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-26ccc5c9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-26ccc5c9{margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-84f50fa3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-84f50fa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-84f50fa3{margin-top:  !important;margin-bottom:  !important;order: initial;background-position: 54% 48%;background-size: cover;background-image: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2025\/03\/Grow-with-your-family_545x307.webp);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-271bf38d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-271bf38d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-271bf38d{padding-top: 20px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab8d0982{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab8d0982 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ab8d0982.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ab8d0982{margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-block-ab8d0982.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-ab8d0982.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3 .uagb-heading-text{font-size: 12px;letter-spacing: 1px;}.uagb-block-f9d54988.wp-block-uagb-separator{text-align: center;}.uagb-block-f9d54988.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f9d54988 .uagb-separator-spacing-wrapper{padding-top: 10px;padding-bottom: 10px;}.uagb-block-f9d54988.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #eabe5e;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__source-image{width: 18px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 18px;height: 18px;font-size: 18px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48a597f8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48a597f8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-48a597f8{margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-22a41c70{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-22a41c70 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-22a41c70{margin-top:  !important;margin-bottom:  !important;order: initial;background-position: 54% 48%;background-size: cover;background-image: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2025\/03\/HelpFamiliesGrow2.webp);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-562935bf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-562935bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-562935bf{padding-top: 20px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5a1442f2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5a1442f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5a1442f2.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5a1442f2{margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-block-5a1442f2.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-5a1442f2.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f .uagb-heading-text{font-size: 12px;letter-spacing: 1px;}.uagb-block-aa17f10e.wp-block-uagb-separator{text-align: center;}.uagb-block-aa17f10e.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-aa17f10e .uagb-separator-spacing-wrapper{padding-top: 10px;padding-bottom: 10px;}.uagb-block-aa17f10e.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #eabe5e;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__source-image{width: 18px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 18px;height: 18px;font-size: 18px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-ced20c64.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 24px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-85559158{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-85559158 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-85559158{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top: 60px !important;margin-bottom: 60px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ea16301a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ea16301a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ea16301a.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ea16301a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-26ccc5c9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-26ccc5c9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-26ccc5c9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #ffffff;;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-84f50fa3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-84f50fa3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-84f50fa3{margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2025\/03\/Grow-with-your-family_545x307.webp);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-271bf38d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-271bf38d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-271bf38d{padding-top: 20px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab8d0982{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab8d0982 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ab8d0982.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-ab8d0982{margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-block-ab8d0982.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-ab8d0982.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3.wp-block-uagb-advanced-heading {padding-left: 40px;}.wp-block-uagb-advanced-heading.uagb-block-d4c1a7e3 .uagb-heading-text{letter-spacing: 4px;}.uagb-block-f9d54988.wp-block-uagb-separator{text-align: center;}.uagb-block-f9d54988.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f9d54988 .uagb-separator-spacing-wrapper{padding-top: 10px;padding-bottom: 10px;}.uagb-block-f9d54988.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #eabe5e;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__source-image{width: 18px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 18px;height: 18px;font-size: 18px;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-cbb8c5bd.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48a597f8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48a597f8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-48a597f8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #ffffff;;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-22a41c70{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-22a41c70 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-22a41c70{margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2025\/03\/HelpFamiliesGrow2.webp);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-562935bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-562935bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-562935bf{padding-top: 20px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5a1442f2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5a1442f2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5a1442f2.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5a1442f2{margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-block-5a1442f2.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-5a1442f2.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f.wp-block-uagb-advanced-heading {padding-left: 40px;}.wp-block-uagb-advanced-heading.uagb-block-d9c0200f .uagb-heading-text{letter-spacing: 4px;}.uagb-block-aa17f10e.wp-block-uagb-separator{text-align: center;}.uagb-block-aa17f10e.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-aa17f10e .uagb-separator-spacing-wrapper{padding-top: 10px;padding-bottom: 10px;}.uagb-block-aa17f10e.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #eabe5e;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__source-image{width: 18px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 18px;height: 18px;font-size: 18px;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-ced20c64 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-ced20c64.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 24px;}}.wp-block-uagb-container.uagb-block-ecebc267 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ecebc267 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ecebc267 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ecebc267 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ecebc267 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ecebc267{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-ecebc267{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(130deg, #ffffff 60%, #f8f8f8 46%);;background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ecebc267{width: 100%;}.wp-block-uagb-container.uagb-block-ecebc267{margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(130deg, #ffffff 60%, #f8f8f8 46%);;background-clip: padding-box;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ecebc267{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-ecebc267{margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(130deg, #ffffff 60%, #f8f8f8 46%);;background-clip: padding-box;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-8d4ac8a0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8d4ac8a0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8d4ac8a0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8d4ac8a0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8d4ac8a0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d4ac8a0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d4ac8a0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-8d4ac8a0{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: 80px;padding-left: 12px;padding-right: 12px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 32px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;max-width: 25% !important;}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;max-width: 25% !important;}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;max-width: 25% !important;}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-047d9c4f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;max-width: 25% !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d4ac8a0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d4ac8a0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8d4ac8a0{padding-top: 80px;padding-bottom: 80px;padding-left: 12px;padding-right: 12px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d4ac8a0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d4ac8a0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8d4ac8a0{padding-top: 80px;padding-bottom: 80px;padding-left: 12px;padding-right: 12px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-047d9c4f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-047d9c4f{margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}}.wp-block-uagb-container.uagb-block-f064f662.wp-block-uagb-container{color: #ffffff;}.wp-block-uagb-container.uagb-block-f064f662.wp-block-uagb-container *{color: #ffffff;}.wp-block-uagb-container.uagb-block-f064f662 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f064f662 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f064f662 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f064f662 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f064f662 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f064f662{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f064f662 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;}.wp-block-uagb-container.uagb-block-f064f662{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 12px;padding-right: 12px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #25282a;;row-gap: 20px;}.wp-block-uagb-container.uagb-block-dbd5f6c0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dbd5f6c0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dbd5f6c0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dbd5f6c0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dbd5f6c0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dbd5f6c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dbd5f6c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-dbd5f6c0{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-dbd5f6c0.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-dbd5f6c0.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.uagb-block-644e4891.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 292px;height: 48px;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-644e4891.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-644e4891.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f064f662{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f064f662 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f064f662{padding-top: 20px;padding-bottom: 20px;padding-left: 12px;padding-right: 12px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #25282a;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dbd5f6c0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dbd5f6c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dbd5f6c0{margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 280px;height: 45px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f064f662{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f064f662 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f064f662{padding-top: 20px;padding-bottom: 20px;padding-left: 12px;padding-right: 12px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #25282a;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dbd5f6c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dbd5f6c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dbd5f6c0{margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-644e4891.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 280px;height: 45px;}}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-beb12949{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-beb12949 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-beb12949{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #006c5b;;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-beb12949{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-beb12949 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-beb12949{margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #006c5b;;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-beb12949{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-beb12949 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-beb12949{margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #006c5b;;}}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-beb12949 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-beb12949{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-beb12949 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-beb12949{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #006c5b;;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-beb12949{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-beb12949 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-beb12949{margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #006c5b;;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-beb12949{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-beb12949 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-beb12949{margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #006c5b;;}}.wp-block-uagb-container.uagb-block-5096eaa1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5096eaa1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5096eaa1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5096eaa1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5096eaa1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5096eaa1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5096eaa1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-5096eaa1{box-shadow: 0px 0px   #00000070 ;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-89b3b7a8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89b3b7a8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89b3b7a8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89b3b7a8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89b3b7a8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89b3b7a8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89b3b7a8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-89b3b7a8{box-shadow: 0px 0px   #00000070 ;padding-top: 2em;padding-bottom: 2em;padding-left: 2em;padding-right: 2em;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: inherit;background-color: #ebebeb;;}.wp-block-uagb-advanced-heading.uagb-block-97ee3d2f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-97ee3d2f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-97ee3d2f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-97ee3d2f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-232092dc.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-232092dc.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-00708611.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: #f3bd48;}.wp-block-uagb-buttons .uagb-block-00708611 .wp-block-button__link{background: #f3bd48;}.wp-block-uagb-buttons .uagb-block-00708611 .wp-block-button__link:hover{background: #f4deaa;}.wp-block-uagb-buttons .uagb-block-00708611 .wp-block-button__link:focus{background: #f4deaa;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-button__wrapper .uagb-buttons-repeater{color: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater.wp-block-button__link{border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-00708611.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-00708611.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater .uagb-button__link{color: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater:hover .uagb-button__link{color: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater:focus .uagb-button__link{color: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: #25282a;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-5096eaa1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5096eaa1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5096eaa1{margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89b3b7a8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89b3b7a8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-89b3b7a8{padding-top: 2px;padding-bottom: 2px;padding-left: 2px;padding-right: 2px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ebebeb;;}.uagb-block-232092dc.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-232092dc.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-00708611.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-5096eaa1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5096eaa1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5096eaa1{margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89b3b7a8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89b3b7a8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-89b3b7a8{padding-top: 2px;padding-bottom: 2px;padding-left: 2px;padding-right: 2px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ebebeb;;}.uagb-block-232092dc.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-232092dc.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-00708611.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-00708611 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}\";s:2:\"js\";s:161:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-00708611' );\n});\n });\";s:18:\"current_block_list\";a:17:{i:0;s:14:\"uagb\/container\";i:1;s:12:\"core\/heading\";i:2;s:9:\"core\/html\";i:3;s:10:\"core\/group\";i:6;s:21:\"uagb\/advanced-heading\";i:7;s:14:\"uagb\/separator\";i:8;s:14:\"uagb\/icon-list\";i:9;s:20:\"uagb\/icon-list-child\";i:10;s:11:\"core\/search\";i:13;s:18:\"core\/legacy-widget\";i:16;s:10:\"uagb\/image\";i:17;s:17:\"core\/social-links\";i:18;s:16:\"core\/social-link\";i:19;s:14:\"core\/paragraph\";i:20;s:30:\"meta-box\/fl-conditional-blocks\";i:21;s:12:\"uagb\/buttons\";i:22;s:18:\"uagb\/buttons-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1778609069;s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:71:\"\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"meta_box":{"_cloudsearch_visibility":"","profile_obj_manual_select":false,"profile_obj":false,"separator":false,"enable_link":false,"login_restricted":"","content_type":"","disclaimer_banner":"","currency":false,"pricing_subtext":false,"element_type":false,"date_field":false,"date_format":false,"theme_header_position":"","post_header_is_sticky":"","is_header_overlay":"","series":false,"ignore_sticky":false,"conditional_blocks_category":false,"cta_selection":false},"uagb_featured_image_src":{"full":["https:\/\/wp-stage.familylife.com\/www\/wp-content\/uploads\/sites\/1001\/2018\/04\/i-never-made-it-to-the-super-bowl_1040x326.jpg",1024,321,true]},"uagb_author_info":{"display_name":"Jill Savage","author_link":"https:\/\/wp-stage.familylife.com\/www\/author\/jill-savage\/"},"uagb_comment_info":0,"uagb_excerpt":"As an NFL quarterback, I yearned to make the big game. But as much as I love football, I realize it can easily distract us from more important goals.","_links":{"self":[{"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/posts\/8278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/users\/222"}],"replies":[{"embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/comments?post=8278"}],"version-history":[{"count":0,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/posts\/8278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/media\/8279"}],"wp:attachment":[{"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/media?parent=8278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/categories?post=8278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/tags?post=8278"},{"taxonomy":"equip-category","embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/equip-category?post=8278"},{"taxonomy":"cwp_profile","embeddable":true,"href":"https:\/\/wp-stage.familylife.com\/www\/wp-json\/wp\/v2\/cwp_profile?post=8278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}